{"id":44,"count":1,"description":"","link":"https:\/\/saintpierredentremont.org\/savoie\/category\/organisation-du-territoire\/communaute-de-communes-coeur-de-chartreuse\/equipements\/","name":"\u00c9quipements","slug":"equipements","taxonomy":"category","parent":43,"meta":[],"_links":{"self":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/categories\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/categories\/43"}],"wp:post_type":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/posts?categories=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}