{"id":10566,"date":"2021-05-25T08:45:22","date_gmt":"2021-05-25T07:45:22","guid":{"rendered":"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor.jpg"},"modified":"2021-05-25T08:45:22","modified_gmt":"2021-05-25T07:45:22","slug":"courrier-assouplissement-des-mesures-sanitaires_fotor","status":"inherit","type":"attachment","link":"https:\/\/saintpierredentremont.org\/savoie\/courrier-assouplissement-des-mesures-sanitaires_fotor\/","title":{"rendered":"courrier assouplissement des mesures sanitaires_Fotor"},"author":12,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-10566","attachment","type-attachment","status-inherit","hentry"],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor-212x300.jpg 212w, https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor.jpg 595w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":595,"height":841,"file":"2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor.jpg","sizes":{"medium":{"file":"courrier-assouplissement-des-mesures-sanitaires_Fotor-212x300.jpg","width":212,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor-212x300.jpg"},"thumbnail":{"file":"courrier-assouplissement-des-mesures-sanitaires_Fotor-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor-150x150.jpg"},"post-thumbnail":{"file":"courrier-assouplissement-des-mesures-sanitaires_Fotor-595x270.jpg","width":595,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor-595x270.jpg"},"full":{"file":"courrier-assouplissement-des-mesures-sanitaires_Fotor.jpg","width":595,"height":841,"mime_type":"image\/jpeg","source_url":"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2021\/05\/courrier-assouplissement-des-mesures-sanitaires_Fotor.jpg","_links":{"self":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/media\/10566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/comments?post=10566"}]}}