{"id":21235,"date":"2026-07-24T16:18:05","date_gmt":"2026-07-24T14:18:05","guid":{"rendered":"https:\/\/saintpierredentremont.org\/savoie\/?p=21235"},"modified":"2026-07-24T16:18:05","modified_gmt":"2026-07-24T14:18:05","slug":"baignade-adoptez-les-bons-reflexes","status":"publish","type":"post","link":"https:\/\/saintpierredentremont.org\/savoie\/baignade-adoptez-les-bons-reflexes\/","title":{"rendered":"Baignade: adoptez les bons r\u00e9flexes"},"content":{"rendered":"<p class=\"font-claude-response-body break-words whitespace-normal\" dir=\"ltr\"><strong>Baignade : attention au risque de cyanobact\u00e9ries<\/strong><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\" dir=\"ltr\">Fortes chaleurs, faible courant, fort ensoleillement : les conditions actuelles favorisent le d\u00e9veloppement des cyanobact\u00e9ries dans nos cours d&rsquo;eau. Certaines produisent des toxines dangereuses pour l&rsquo;Homme et les animaux.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\" dir=\"ltr\">Il est donc fortement d\u00e9conseill\u00e9 de se baigner dans le Guiers ou tout autre cours d&rsquo;eau non surveill\u00e9, et d&rsquo;y laisser vos animaux se baigner ou boire.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\" dir=\"ltr\">Retrouvez tous les d\u00e9tails ci-dessous et la liste des sites de baignade contr\u00f4l\u00e9s sur <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/baignades.sante.gouv.fr\/\">baignades.sante.gouv.fr<\/a>.<\/p>\n<p dir=\"ltr\"><a href=\"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-24-a-16.16.36.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21236\" src=\"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-24-a-16.16.36-725x1024.png\" alt=\"SIAGA baignade\" width=\"604\" height=\"853\" srcset=\"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-24-a-16.16.36-725x1024.png 725w, https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-24-a-16.16.36-212x300.png 212w, https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-24-a-16.16.36-768x1084.png 768w, https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-24-a-16.16.36-1088x1536.png 1088w, https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-24-a-16.16.36-1451x2048.png 1451w, https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-24-a-16.16.36.png 1690w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Baignade : attention au risque de cyanobact\u00e9ries Fortes chaleurs, faible courant, fort ensoleillement : les conditions actuelles favorisent le d\u00e9veloppement des cyanobact\u00e9ries dans nos cours d&rsquo;eau. Certaines produisent des toxines dangereuses pour l&rsquo;Homme et les animaux. Il est donc fortement d\u00e9conseill\u00e9 de se baigner dans le Guiers ou tout autre cours d&rsquo;eau non surveill\u00e9, et [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1280,1407],"tags":[130,253,1507,1624,1625],"class_list":["post-21235","post","type-post","status-publish","format-standard","hentry","category-leau","category-z_actualites-en-page-accueil","tag-eau-2","tag-ete","tag-1507","tag-siaga","tag-cyanobacterie"],"publishpress_future_action":{"enabled":false,"date":"2026-09-10 01:43:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/posts\/21235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/comments?post=21235"}],"version-history":[{"count":1,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/posts\/21235\/revisions"}],"predecessor-version":[{"id":21237,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/posts\/21235\/revisions\/21237"}],"wp:attachment":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/media?parent=21235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/categories?post=21235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/tags?post=21235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}