{"id":6242,"date":"2019-03-26T17:25:23","date_gmt":"2019-03-26T16:25:23","guid":{"rendered":"https:\/\/saintpierredentremont.org\/savoie\/?p=6242"},"modified":"2019-03-26T17:25:23","modified_gmt":"2019-03-26T16:25:23","slug":"le-reglement-sanitaire-departemental-de-la-savoie","status":"publish","type":"post","link":"https:\/\/saintpierredentremont.org\/savoie\/le-reglement-sanitaire-departemental-de-la-savoie\/","title":{"rendered":"Le r\u00e8glement sanitaire d\u00e9partemental de la Savoie"},"content":{"rendered":"<p><strong>Le r\u00e8glement sanitaire d\u00e9partemental aborde l&rsquo;ensemble des r\u00e8gles sanitaires applicables<\/strong><\/p>\n<ol>\n<li>Les eaux destin\u00e9es \u00e0 la consommation humaine<\/li>\n<li>Locaux d&rsquo;habitation et assimil\u00e9s<\/li>\n<li>Dispositions applicables aux b\u00e2timents autres que ceux \u00e0 usage d&rsquo;habitation et assimil\u00e9s<\/li>\n<li>Elimination des d\u00e9chets et mesures de salubrit\u00e9 g\u00e9n\u00e9rales<\/li>\n<li>Le bruit<\/li>\n<li>Mesures visant les malades contagieux, leur entourage et leur environnement<\/li>\n<li>Hygi\u00e8ne de l&rsquo;alimentation<\/li>\n<li>Prescription applicables aux activit\u00e9s d&rsquo;\u00e9levage et autres activit\u00e9s agricoles<\/li>\n<li>Dispositions diverses<\/li>\n<\/ol>\n<h2>Document t\u00e9l\u00e9chargeable<\/h2>\n<p><a href=\"https:\/\/saintpierredentremont.org\/savoie\/wp-content\/uploads\/2019\/03\/Reglement-Sanitaire-de--partemental-SAVOIE.pdf\" target=\"_blank\" rel=\"noopener\">R\u00e8glement Sanitaire d\u00e9partemental &#8211; SAVOIE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00e8glement sanitaire d\u00e9partemental aborde l&rsquo;ensemble des r\u00e8gles sanitaires applicables Les eaux destin\u00e9es \u00e0 la consommation humaine Locaux d&rsquo;habitation et assimil\u00e9s Dispositions applicables aux b\u00e2timents autres que ceux \u00e0 usage d&rsquo;habitation et assimil\u00e9s Elimination des d\u00e9chets et mesures de salubrit\u00e9 g\u00e9n\u00e9rales Le bruit Mesures visant les malades contagieux, leur entourage et leur environnement Hygi\u00e8ne de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[294],"tags":[285,335,604,878,879,880,881],"class_list":["post-6242","post","type-post","status-publish","format-standard","hentry","category-reglementation","tag-bruit","tag-dechet","tag-alimentation","tag-reglement-sanitaire","tag-hygiene","tag-elevage","tag-salubrite"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:18:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/posts\/6242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/comments?post=6242"}],"version-history":[{"count":1,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/posts\/6242\/revisions"}],"predecessor-version":[{"id":6244,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/posts\/6242\/revisions\/6244"}],"wp:attachment":[{"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/media?parent=6242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/categories?post=6242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saintpierredentremont.org\/savoie\/wp-json\/wp\/v2\/tags?post=6242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}